{"id":10867,"date":"2021-09-09T14:40:07","date_gmt":"2021-09-09T14:40:07","guid":{"rendered":"https:\/\/stagingdsd.kinsta.cloud\/atencion\/"},"modified":"2021-09-09T14:41:11","modified_gmt":"2021-09-09T14:41:11","slug":"atencion","status":"publish","type":"page","link":"https:\/\/dayseaday.nl\/es\/atencion\/","title":{"rendered":"Atenci\u00f3n"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10867\" class=\"elementor elementor-10867 elementor-195\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-cbdb728 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-eae-slider=\"37524\" data-id=\"cbdb728\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;e7c7319&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d7cfb1\" data-eae-slider=\"6105\" data-id=\"3d7cfb1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa7474b elementor-widget elementor-widget-heading\" data-id=\"aa7474b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Atenci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fdcc58 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1fdcc58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#Atenci\u00f3n\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-d515f18 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"78283\" data-id=\"d515f18\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;fa90f84&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f98bf45\" data-eae-slider=\"22354\" data-id=\"f98bf45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2a5c4b elementor-widget elementor-widget-menu-anchor\" data-id=\"f2a5c4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"atencin\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c551586 elementor-nav-menu__align-start elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"c551586\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fa\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-background e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-c551586\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-11033\"><a href=\"https:\/\/dayseaday.nl\/es\/pasion\/\" class=\"elementor-item\">Pasi\u00f3n<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-11034\"><a href=\"https:\/\/dayseaday.nl\/es\/solidez\/\" class=\"elementor-item\">Solidez<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-11035\"><a href=\"https:\/\/dayseaday.nl\/es\/atencion\/\" class=\"elementor-item\">Atenci\u00f3n<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-11036\"><a href=\"https:\/\/dayseaday.nl\/es\/historia\/\" class=\"elementor-item\">Historia<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-11037\"><a href=\"https:\/\/dayseaday.nl\/es\/nuestro-equipo\/\" class=\"elementor-item\">Nuestro equipo<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Alternar men\u00fa\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-c551586\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-11033\"><a href=\"https:\/\/dayseaday.nl\/es\/pasion\/\" class=\"elementor-item\" tabindex=\"-1\">Pasi\u00f3n<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-11034\"><a href=\"https:\/\/dayseaday.nl\/es\/solidez\/\" class=\"elementor-item\" tabindex=\"-1\">Solidez<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-11035\"><a href=\"https:\/\/dayseaday.nl\/es\/atencion\/\" class=\"elementor-item\" tabindex=\"-1\">Atenci\u00f3n<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-11036\"><a href=\"https:\/\/dayseaday.nl\/es\/historia\/\" class=\"elementor-item\" tabindex=\"-1\">Historia<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-11037\"><a href=\"https:\/\/dayseaday.nl\/es\/nuestro-equipo\/\" class=\"elementor-item\" tabindex=\"-1\">Nuestro equipo<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-ee5e52c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"28804\" data-id=\"ee5e52c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;6fdf25f&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6aebb3d\" data-eae-slider=\"3959\" data-id=\"6aebb3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-809a9d0 elementor-widget elementor-widget-shortcode\" data-id=\"809a9d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"11185\" class=\"elementor elementor-11185 elementor-399 elementor-399\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-e691b5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"58345\" data-id=\"e691b5e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;c6a5575&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-75599be\" data-eae-slider=\"98879\" data-id=\"75599be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76510db elementor-widget elementor-widget-heading\" data-id=\"76510db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">NUESTRO ENFOQUE<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcc97e7 elementor-widget elementor-widget-heading\" data-id=\"dcc97e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Empresa sostenible y responsable<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f87dd4 elementor-widget elementor-widget-text-editor\" data-id=\"5f87dd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dayseaday presta atenci\u00f3n al paquete completo. Adem\u00e1s de suministrar nuestros productos, nos gusta hablar con el cliente del envasado, la distribuci\u00f3n y otros asuntos importantes para usted. Dayseaday cuenta con un equipo motivado que utiliza las instalaciones y m\u00e1quinas m\u00e1s modernas con gran entusiasmo.<\/p>\n<p>Todo ello nos permite entregar y garantizar nuestros productos conforme a sus exigencias.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c1be081\" data-eae-slider=\"96212\" data-id=\"c1be081\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24b474b elementor-widget elementor-widget-video\" data-id=\"24b474b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"Reproductor de v\u00eddeo vimeo\" src=\"https:\/\/player.vimeo.com\/video\/588725048?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-af82712 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-eae-slider=\"41249\" data-id=\"af82712\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;29af821&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6649595\" data-eae-slider=\"11495\" data-id=\"6649595\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff3db86 eael-infobox-icon-bg-shape-circle eael-infobox-content-align--center eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"ff3db86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <i aria-hidden=\"true\" class=\"fas fa-check-circle\"><\/i>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h2 class=\"title\">PAQUETE TOTAL<\/h2>            <\/div>\n            <div><p>Estaremos encantados de hablar con usted del envasado, la distribuci\u00f3n y otras cuestiones importantes para usted.<\/p>\n<\/div>        <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e0d4aef\" data-eae-slider=\"34968\" data-id=\"e0d4aef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04963f2 eael-infobox-icon-bg-shape-circle eael-infobox-content-align--center eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"04963f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <i aria-hidden=\"true\" class=\"fas fa-gem\"><\/i>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h2 class=\"title\">CALIDAD<\/h2>            <\/div>\n            <div><p>Suministramos productos sostenibles que no solo cumplen todos los requisitos est\u00e1ndar, sino que adem\u00e1s cuentan, por ejemplo, con las certificaciones ASC o MSC.<\/p>\n<\/div>        <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-aa17f30\" data-eae-slider=\"60104\" data-id=\"aa17f30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d809ccd eael-infobox-icon-bg-shape-circle eael-infobox-content-align--center eael-infobox-icon-hover-bg-shape-none elementor-widget elementor-widget-eael-info-box\" data-id=\"d809ccd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-info-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-infobox icon-on-top\">\n\t            <div class=\"infobox-icon eael-icon-only\">\n\n            \n                            <div class=\"infobox-icon-wrap\">\n                    <i aria-hidden=\"true\" class=\"fas fa-handshake\"><\/i>                <\/div>\n            \n            \n        <\/div>\n            <div class=\"infobox-content eael-icon-only\">\n                    <div class=\"infobox-title-section\">\n                <h2 class=\"title\">EQUIPO MOTIVADO<\/h2>            <\/div>\n            <div><p>Dayseaday cuenta con un equipo motivado que utiliza las instalaciones y m\u00e1quinas m\u00e1s modernas con gran entusiasmo.<\/p>\n<\/div>        <\/div>\n            <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Atenci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10867","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atenci\u00f3n - Dayseaday<\/title>\n<meta name=\"description\" content=\"Sinds 1986 is de Dayseaday Group een toonaangevende handelspartner in verse en diepgevroren visproducten.De Dayseaday Group is uitgebreid door autonome groei en overnames in binnen- en buitenland en doet nu wereldwijd zaken in meer dan 50 landen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dayseaday.nl\/es\/atencion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atenci\u00f3n - Dayseaday\" \/>\n<meta property=\"og:description\" content=\"Sinds 1986 is de Dayseaday Group een toonaangevende handelspartner in verse en diepgevroren visproducten.De Dayseaday Group is uitgebreid door autonome groei en overnames in binnen- en buitenland en doet nu wereldwijd zaken in meer dan 50 landen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dayseaday.nl\/es\/atencion\/\" \/>\n<meta property=\"og:site_name\" content=\"Dayseaday\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Dayseaday\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-09T14:41:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dayseaday.nl\/wp-content\/uploads\/2024\/03\/dsdcover.jpg.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"899\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@dayseaday\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dayseaday.nl\/es\/atencion\/\",\"url\":\"https:\/\/dayseaday.nl\/es\/atencion\/\",\"name\":\"Atenci\u00f3n - Dayseaday\",\"isPartOf\":{\"@id\":\"\/#website\"},\"datePublished\":\"2021-09-09T14:40:07+00:00\",\"dateModified\":\"2021-09-09T14:41:11+00:00\",\"description\":\"Sinds 1986 is de Dayseaday Group een toonaangevende handelspartner in verse en diepgevroren visproducten.De Dayseaday Group is uitgebreid door autonome groei en overnames in binnen- en buitenland en doet nu wereldwijd zaken in meer dan 50 landen.\",\"breadcrumb\":{\"@id\":\"https:\/\/dayseaday.nl\/es\/atencion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dayseaday.nl\/es\/atencion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dayseaday.nl\/es\/atencion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dayseaday.nl\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atenci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/#website\",\"url\":\"\/\",\"name\":\"Dayseaday\",\"description\":\"Fresh and Frozen fish products\",\"publisher\":{\"@id\":\"\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"\/#organization\",\"name\":\"Dayseaday Group\",\"url\":\"\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dayseaday.nl\/wp-content\/uploads\/2020\/08\/dsd-logo.png\",\"contentUrl\":\"https:\/\/dayseaday.nl\/wp-content\/uploads\/2020\/08\/dsd-logo.png\",\"width\":1179,\"height\":473,\"caption\":\"Dayseaday Group\"},\"image\":{\"@id\":\"\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Dayseaday\",\"https:\/\/x.com\/dayseaday\",\"https:\/\/www.instagram.com\/dayseaday\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atenci\u00f3n - Dayseaday","description":"Sinds 1986 is de Dayseaday Group een toonaangevende handelspartner in verse en diepgevroren visproducten.De Dayseaday Group is uitgebreid door autonome groei en overnames in binnen- en buitenland en doet nu wereldwijd zaken in meer dan 50 landen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dayseaday.nl\/es\/atencion\/","og_locale":"es_ES","og_type":"article","og_title":"Atenci\u00f3n - Dayseaday","og_description":"Sinds 1986 is de Dayseaday Group een toonaangevende handelspartner in verse en diepgevroren visproducten.De Dayseaday Group is uitgebreid door autonome groei en overnames in binnen- en buitenland en doet nu wereldwijd zaken in meer dan 50 landen.","og_url":"https:\/\/dayseaday.nl\/es\/atencion\/","og_site_name":"Dayseaday","article_publisher":"https:\/\/www.facebook.com\/Dayseaday","article_modified_time":"2021-09-09T14:41:11+00:00","og_image":[{"width":1600,"height":899,"url":"https:\/\/dayseaday.nl\/wp-content\/uploads\/2024\/03\/dsdcover.jpg.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@dayseaday","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dayseaday.nl\/es\/atencion\/","url":"https:\/\/dayseaday.nl\/es\/atencion\/","name":"Atenci\u00f3n - Dayseaday","isPartOf":{"@id":"\/#website"},"datePublished":"2021-09-09T14:40:07+00:00","dateModified":"2021-09-09T14:41:11+00:00","description":"Sinds 1986 is de Dayseaday Group een toonaangevende handelspartner in verse en diepgevroren visproducten.De Dayseaday Group is uitgebreid door autonome groei en overnames in binnen- en buitenland en doet nu wereldwijd zaken in meer dan 50 landen.","breadcrumb":{"@id":"https:\/\/dayseaday.nl\/es\/atencion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dayseaday.nl\/es\/atencion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dayseaday.nl\/es\/atencion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dayseaday.nl\/es\/"},{"@type":"ListItem","position":2,"name":"Atenci\u00f3n"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Dayseaday","description":"Fresh and Frozen fish products","publisher":{"@id":"\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"\/#organization","name":"Dayseaday Group","url":"\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"\/#\/schema\/logo\/image\/","url":"https:\/\/dayseaday.nl\/wp-content\/uploads\/2020\/08\/dsd-logo.png","contentUrl":"https:\/\/dayseaday.nl\/wp-content\/uploads\/2020\/08\/dsd-logo.png","width":1179,"height":473,"caption":"Dayseaday Group"},"image":{"@id":"\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Dayseaday","https:\/\/x.com\/dayseaday","https:\/\/www.instagram.com\/dayseaday\/"]}]}},"_links":{"self":[{"href":"https:\/\/dayseaday.nl\/es\/wp-json\/wp\/v2\/pages\/10867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dayseaday.nl\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dayseaday.nl\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dayseaday.nl\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dayseaday.nl\/es\/wp-json\/wp\/v2\/comments?post=10867"}],"version-history":[{"count":0,"href":"https:\/\/dayseaday.nl\/es\/wp-json\/wp\/v2\/pages\/10867\/revisions"}],"wp:attachment":[{"href":"https:\/\/dayseaday.nl\/es\/wp-json\/wp\/v2\/media?parent=10867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}